{"id":478,"count":1,"description":"","link":"https:\/\/alax.info\/blog\/tag\/capabilities","name":"capabilities","slug":"capabilities","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/alax.info\/blog\/wp-json\/wp\/v2\/tags\/478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alax.info\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/alax.info\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/alax.info\/blog\/wp-json\/wp\/v2\/posts?tags=478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}